{"id":229,"count":1,"description":"","link":"https:\/\/dentalvision.co.th\/th\/brand\/aesculap\/","name":"Aesculap","slug":"aesculap","taxonomy":"brand","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aesculap Archives - Dental Vision<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dentalvision.co.th\/th\/brand\/aesculap\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aesculap Archives - Dental Vision\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dentalvision.co.th\/th\/brand\/aesculap\/\" \/>\n<meta property=\"og:site_name\" content=\"Dental Vision\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/dentalvision.co.th\/th\/brand\/aesculap\/\",\"url\":\"https:\/\/dentalvision.co.th\/th\/brand\/aesculap\/\",\"name\":\"Aesculap Archives - Dental Vision\",\"isPartOf\":{\"@id\":\"https:\/\/dentalvision.co.th\/th\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/dentalvision.co.th\/th\/brand\/aesculap\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dentalvision.co.th\/th\/brand\/aesculap\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dentalvision.co.th\/th\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aesculap\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dentalvision.co.th\/th\/#website\",\"url\":\"https:\/\/dentalvision.co.th\/th\/\",\"name\":\"Dental Vision\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dentalvision.co.th\/th\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dentalvision.co.th\/th\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dentalvision.co.th\/th\/#organization\",\"name\":\"Dental Vision\",\"url\":\"https:\/\/dentalvision.co.th\/th\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dentalvision.co.th\/th\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dentalvision.co.th\/th\/wp-content\/uploads\/2024\/10\/Group.png\",\"contentUrl\":\"https:\/\/dentalvision.co.th\/th\/wp-content\/uploads\/2024\/10\/Group.png\",\"width\":148,\"height\":31,\"caption\":\"Dental Vision\"},\"image\":{\"@id\":\"https:\/\/dentalvision.co.th\/th\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aesculap Archives - Dental Vision","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dentalvision.co.th\/th\/brand\/aesculap\/","og_locale":"en_US","og_type":"article","og_title":"Aesculap Archives - Dental Vision","og_url":"https:\/\/dentalvision.co.th\/th\/brand\/aesculap\/","og_site_name":"Dental Vision","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/dentalvision.co.th\/th\/brand\/aesculap\/","url":"https:\/\/dentalvision.co.th\/th\/brand\/aesculap\/","name":"Aesculap Archives - Dental Vision","isPartOf":{"@id":"https:\/\/dentalvision.co.th\/th\/#website"},"breadcrumb":{"@id":"https:\/\/dentalvision.co.th\/th\/brand\/aesculap\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/dentalvision.co.th\/th\/brand\/aesculap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dentalvision.co.th\/th\/"},{"@type":"ListItem","position":2,"name":"Aesculap"}]},{"@type":"WebSite","@id":"https:\/\/dentalvision.co.th\/th\/#website","url":"https:\/\/dentalvision.co.th\/th\/","name":"Dental Vision","description":"","publisher":{"@id":"https:\/\/dentalvision.co.th\/th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dentalvision.co.th\/th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dentalvision.co.th\/th\/#organization","name":"Dental Vision","url":"https:\/\/dentalvision.co.th\/th\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dentalvision.co.th\/th\/#\/schema\/logo\/image\/","url":"https:\/\/dentalvision.co.th\/th\/wp-content\/uploads\/2024\/10\/Group.png","contentUrl":"https:\/\/dentalvision.co.th\/th\/wp-content\/uploads\/2024\/10\/Group.png","width":148,"height":31,"caption":"Dental Vision"},"image":{"@id":"https:\/\/dentalvision.co.th\/th\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dentalvision.co.th\/th\/wp-json\/wp\/v2\/brand\/229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dentalvision.co.th\/th\/wp-json\/wp\/v2\/brand"}],"about":[{"href":"https:\/\/dentalvision.co.th\/th\/wp-json\/wp\/v2\/taxonomies\/brand"}],"wp:post_type":[{"href":"https:\/\/dentalvision.co.th\/th\/wp-json\/wp\/v2\/product?brand=229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}